{"id":2782,"date":"2016-09-28T13:45:48","date_gmt":"2016-09-28T11:45:48","guid":{"rendered":"https:\/\/www.goebl-architecture.com\/wp-content\/uploads\/2016\/09\/herzogenburg-dachgleiche-2.jpg"},"modified":"2016-09-28T13:50:09","modified_gmt":"2016-09-28T11:50:09","slug":"herzogenburg-dachgleiche-2","status":"inherit","type":"attachment","link":"https:\/\/www.goebl-architecture.com\/de\/rathaus-herzogenburg-dachgleichenfeier\/herzogenburg-dachgleiche-2\/","title":{"rendered":"herzogenburg-dachgleiche-2"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-2782","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.goebl-architecture.com\/wp-content\/uploads\/2016\/09\/herzogenburg-dachgleiche-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1335\" src=\"https:\/\/www.goebl-architecture.com\/wp-content\/uploads\/2016\/09\/herzogenburg-dachgleiche-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.goebl-architecture.com\/wp-content\/uploads\/2016\/09\/herzogenburg-dachgleiche-2.jpg 2000w, https:\/\/www.goebl-architecture.com\/wp-content\/uploads\/2016\/09\/herzogenburg-dachgleiche-2-1920x1282.jpg 1920w\" sizes=\"auto, (max-width: 2000px) 100vw, 2000px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2000,"height":1335,"file":"2016\/09\/herzogenburg-dachgleiche-2.jpg","sizes":{"thumbnail":{"file":"herzogenburg-dachgleiche-2-100x100.jpg","width":100,"height":100,"mime_type":"image\/jpeg","source_url":"https:\/\/www.goebl-architecture.com\/wp-content\/uploads\/2016\/09\/herzogenburg-dachgleiche-2-100x100.jpg"},"large":{"file":"herzogenburg-dachgleiche-2-1920x1282.jpg","width":1920,"height":1282,"mime_type":"image\/jpeg","source_url":"https:\/\/www.goebl-architecture.com\/wp-content\/uploads\/2016\/09\/herzogenburg-dachgleiche-2-1920x1282.jpg"},"full":{"file":"herzogenburg-dachgleiche-2.jpg","width":2000,"height":1335,"mime_type":"image\/jpeg","source_url":"https:\/\/www.goebl-architecture.com\/wp-content\/uploads\/2016\/09\/herzogenburg-dachgleiche-2.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":2775,"source_url":"https:\/\/www.goebl-architecture.com\/wp-content\/uploads\/2016\/09\/herzogenburg-dachgleiche-2.jpg","filename":"herzogenburg-dachgleiche-2.jpg","filesize":1871019,"_links":{"self":[{"href":"https:\/\/www.goebl-architecture.com\/de\/wp-json\/wp\/v2\/media\/2782","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.goebl-architecture.com\/de\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.goebl-architecture.com\/de\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.goebl-architecture.com\/de\/wp-json\/wp\/v2\/users\/1"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":2775,"href":"https:\/\/www.goebl-architecture.com\/de\/wp-json\/wp\/v2\/posts\/2775"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}